{"id":6088,"date":"2025-10-23T18:16:49","date_gmt":"2025-10-23T18:16:49","guid":{"rendered":"https:\/\/bolas.golf\/?p=6088"},"modified":"2025-10-23T18:16:49","modified_gmt":"2025-10-23T18:16:49","slug":"los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono","status":"publish","type":"post","link":"https:\/\/bolas.golf\/en\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/","title":{"rendered":"PGA Tour winners won&#039;t be traveling to Kapalua or Augusta National this fall."},"content":{"rendered":"<p><html><body><\/p>\n<p>La tradici\u00f3n de que los ganadores del PGA Tour en oto\u00f1o accedieran a eventos como Kapalua y Augusta National ha cambiado. Anteriormente, ganar en la parte de oto\u00f1o del FedEx Cup garantizaba un lugar en The Sentry en Kapalua, una invitaci\u00f3n al Masters en abril y una exenci\u00f3n de dos a\u00f1os en el tour. Aunque la exenci\u00f3n de dos a\u00f1os sigue vigente, Augusta National ha modificado sus criterios, eliminando el acceso autom\u00e1tico para los ganadores de oto\u00f1o y optando por los ganadores de seis torneos nacionales designados en todo el mundo.<\/p>\n<p>Este a\u00f1o, Kapalua no se llevar\u00e1 a cabo debido a una escasez de agua provocada por la sequ\u00eda y problemas con un sistema de entrega de agua que tiene m\u00e1s de un siglo. El campo Plantation cerr\u00f3 el 2 de septiembre y la PGA Tour determin\u00f3 que no podr\u00eda estar listo para el inicio de la temporada. Hace un mes, se anunci\u00f3 que Kapalua no albergar\u00eda The Sentry, y cada vez es m\u00e1s probable que el torneo sea cancelado en lugar de trasladarse a un sitio temporal en la Costa Oeste o en Florida.<\/p>\n<p>La situaci\u00f3n plantea preguntas sobre qu\u00e9 suceder\u00e1 con jugadores como Steven Fisk, quien gan\u00f3 el Sanderson Farms como su primera victoria en el PGA Tour, as\u00ed como con William Mouw y Karl Vilips, quienes tambi\u00e9n ganaron torneos este a\u00f1o pero no lograron entrar en el top 50 del FedEx Cup.<\/p>\n<h2>Posibles alternativas para los jugadores<\/h2>\n<p>Una posibilidad es encontrar otro evento destacado con un premio de 20 millones de d\u00f3lares para que estos jugadores compitan, ya sea en Pebble Beach, que ya tiene un campo de 80 jugadores para el pro-am, o d\u00e1ndoles la opci\u00f3n de elegir entre diferentes torneos. Si se cancela el evento, el Sony Open, programado del 15 al 18 de enero, ser\u00eda el inicio del calendario del PGA Tour por primera vez, convirti\u00e9ndose en el s\u00e9ptimo torneo en tener esa distinci\u00f3n. Adem\u00e1s, ser\u00eda el inicio m\u00e1s tard\u00edo de un a\u00f1o del PGA Tour desde que comenz\u00f3 la era moderna en 1969.<\/p>\n<h2>Dustin Johnson en la International Series<\/h2>\n<p>En otro \u00e1mbito, la International Series del Asian Tour cuenta con 15 jugadores de LIV Golf en Filipinas esta semana, adem\u00e1s de tres que jugaron como reservas. Dustin Johnson, ex n\u00famero uno del mundo, es uno de los nombres destacados. Desde que firm\u00f3 con la liga financiada por Arabia Saudita en 2022, no ha competido fuera de LIV Golf, excepto en el Saudi International en 2024 y el Dunhill Links Championship este mes junto a su suegro Wayne Gretzky. Con un calendario completo de LIV, Johnson ha participado en 20 torneos este a\u00f1o, su mayor cantidad desde 2021.<\/p>\n<p>\u201cLo que m\u00e1s amo del golf es que me lleva a lugares que de otro modo nunca habr\u00eda visitado, y Filipinas es uno de esos lugares\u201d, coment\u00f3 Johnson. Tambi\u00e9n destac\u00f3 que \u201cla International Series es un ajuste perfecto para donde estoy en mi carrera\u201d. A pesar de que la temporada de LIV Golf ha terminado, Johnson expres\u00f3 su deseo de seguir compitiendo y desafi\u00e1ndose contra algunos de los mejores jugadores.<\/p>\n<h2>Proyecciones para el oto\u00f1o de 2026<\/h2>\n<p>El PGA Tour regresar\u00e1 a Black Desert con un nuevo patrocinador (Bank of Utah) y un premio menor, de 6 millones de d\u00f3lares, en comparaci\u00f3n con los 7.5 millones del a\u00f1o pasado. Esto es com\u00fan en todos los torneos de la parte de oto\u00f1o del FedEx Cup. En 2023, la PGA Tour tuvo siete eventos de oto\u00f1o con un premio total de 56.6 millones de d\u00f3lares, casi todos con premios de 8 millones o m\u00e1s. El a\u00f1o pasado, hubo ocho torneos con 58.3 millones en premios. Las Vegas ya no forma parte del calendario, y los siete torneos de 2025 tendr\u00e1n un fondo total de 45 millones de d\u00f3lares.<\/p>\n<p>El futuro del calendario de oto\u00f1o del pr\u00f3ximo a\u00f1o sigue en desarrollo, ya que el patrocinio del torneo de Mississippi finaliz\u00f3 este a\u00f1o. La PGA Tour ha a\u00f1adido el Good Good Championship para Austin, Texas, en noviembre de 2026. Adem\u00e1s, se espera que el Mexico Open, que segu\u00eda a la gira por la Costa Oeste, se traslade a la parte de oto\u00f1o del calendario.<\/p>\n<h2>Victoria en casa para Sei Young Kim<\/h2>\n<p>Sei Young Kim, quien gan\u00f3 cinco veces en dos a\u00f1os en la LPGA de Corea y luego se destac\u00f3 en la LPGA, logr\u00f3 su primera victoria en casa en el BMW Ladies Championship, rompiendo una sequ\u00eda de cinco a\u00f1os sin t\u00edtulos. \u201cMe tom\u00f3 m\u00e1s de 10 a\u00f1os ganar en frente de mi familia y amigos\u201d, dijo Kim tras su victoria por cuatro golpes. \u201cSignifica mucho para m\u00ed. Es un torneo que realmente quer\u00eda ganar, y no puedo expresar con palabras todo lo que siento.<\/p>\n<p>La energ\u00eda de los fans fue incre\u00edble y estoy muy agradecida por ello.\u201d Ahora, Kim busca repetir su \u00e9xito en el International Crown en Corea del Sur.<\/p>\n<h2>Notas breves<\/h2>\n<p>Lauryn Nguyen, quien ayud\u00f3 a Northwestern a ganar un t\u00edtulo de la NCAA en golf femenino, ha sido seleccionada para hacer su debut profesional en la LPGA en The Annika el pr\u00f3ximo mes en Pelican Golf Club. Nguyen fue elegida por su desempe\u00f1o en el golf y su trabajo organizando un evento juvenil en su ciudad natal de Seattle, adem\u00e1s de gestionar la Duc Foundation que otorga becas a ni\u00f1os necesitados.<\/p>\n<p>El PGA Professional Championship se llevar\u00e1 a cabo en Superstition Mountain en Arizona en 2028, dos a\u00f1os despu\u00e9s de que la versi\u00f3n senior del torneo se realice all\u00ed. Maverick McNealy es el \u00fanico jugador en el Bank of Utah Championship que lleg\u00f3 al Tour Championship este a\u00f1o.<\/p>\n<h2>Estad\u00edstica de la semana<\/h2>\n<p>Tres jugadores europeos de la Ryder Cup est\u00e1n fuera del top 70 en la carrera hacia Dub\u00e1i: Ludvig Aberg (75), Shane Lowry (107) y Sepp Straka (148).<\/p>\n<h2>Palabras finales<\/h2>\n<p>\u201cCreo que el golf puede crecer, pero debe hacerlo de una manera en la que las personas que llegan al juego respeten y reconozcan que esto es un poco diferente a otros deportes.\u201d \u2014 Rory McIlroy.<\/p>\n<p><\/body><\/html><\/p>\n<p><script type='application\/ld+json'>\n{\"@context\": \"https:\/\/schema.org\", \"@type\": \"NewsArticle\", \"headline\": \"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o\", \"datePublished\": \"2025-10-23T18:07:02.627820+00:00\", \"dateModified\": \"2025-10-23T18:08:32.094994+00:00\", \"description\": \"Noticias Golf: Los ganadores del PGA Tour ya no tendr\u00e1n acceso a Kapalua ni a Augusta National en oto\u00f1o, tras cambios en las reglas. Noticia\", \"mainEntityOfPage\": \"https:\/\/bolas.golf\", \"image\": [\"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/10\/golf_1761242909.jpg\"]}\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Changes to the PGA Tour eliminate the tradition of fall winners getting access to Kapalua and Augusta National, affecting several players.<\/p>","protected":false},"author":1,"featured_media":6087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[272,277],"tags":[273],"class_list":["post-6088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-golf","category-pga-tour","tag-noticias-golf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o<\/title>\n<meta name=\"description\" content=\"\u26f3 Te pongo al d\u00eda de toda la actualidad en el PGA tour, han quitado lo de las plazas regalo para Kapalua y Augusta National!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolas.golf\/en\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/\"},\"author\":{\"name\":\"Redactor general\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/person\\\/9bcd4ea4ff7918f8583a85dbc55a3764\"},\"headline\":\"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o\",\"datePublished\":\"2025-10-23T18:16:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/\"},\"wordCount\":1067,\"publisher\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golf_1761242909.jpg\",\"keywords\":[\"Noticias Golf\"],\"articleSection\":[\"Noticias Golf\",\"PGA Tour\"],\"inLanguage\":\"en-US\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/\",\"url\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/\",\"name\":\"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golf_1761242909.jpg\",\"datePublished\":\"2025-10-23T18:16:49+00:00\",\"description\":\"\u26f3 Te pongo al d\u00eda de toda la actualidad en el PGA tour, han quitado lo de las plazas regalo para Kapalua y Augusta National!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golf_1761242909.jpg\",\"contentUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/golf_1761242909.jpg\",\"width\":1440,\"height\":810,\"caption\":\"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o \u2013 imagen editorial de golf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bolas.golf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bolas.golf\\\/en\\\/\",\"name\":\"BOLAS.GOLF\",\"description\":\"Tu especialista en bolas de golf\",\"publisher\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bolas.golf\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\",\"name\":\"BOLAS.GOLF\",\"url\":\"https:\\\/\\\/bolas.golf\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp\",\"contentUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp\",\"width\":512,\"height\":165,\"caption\":\"BOLAS.GOLF\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/person\\\/9bcd4ea4ff7918f8583a85dbc55a3764\",\"name\":\"Redactor general\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"caption\":\"Redactor general\"},\"sameAs\":[\"http:\\\/\\\/casaclub.golf\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PGA Tour winners won&#039;t be traveling to Kapalua or Augusta National this fall.","description":"\u26f3 I&#039;ll keep you up to date on all the latest news from the PGA Tour; they&#039;ve removed the free spots for Kapalua and Augusta National!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolas.golf\/en\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#article","isPartOf":{"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/"},"author":{"name":"Redactor general","@id":"https:\/\/bolas.golf\/en\/#\/schema\/person\/9bcd4ea4ff7918f8583a85dbc55a3764"},"headline":"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o","datePublished":"2025-10-23T18:16:49+00:00","mainEntityOfPage":{"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/"},"wordCount":1067,"publisher":{"@id":"https:\/\/bolas.golf\/en\/#organization"},"image":{"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#primaryimage"},"thumbnailUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/10\/golf_1761242909.jpg","keywords":["Noticias Golf"],"articleSection":["Noticias Golf","PGA Tour"],"inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/","url":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/","name":"PGA Tour winners won&#039;t be traveling to Kapalua or Augusta National this fall.","isPartOf":{"@id":"https:\/\/bolas.golf\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#primaryimage"},"image":{"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#primaryimage"},"thumbnailUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/10\/golf_1761242909.jpg","datePublished":"2025-10-23T18:16:49+00:00","description":"\u26f3 I&#039;ll keep you up to date on all the latest news from the PGA Tour; they&#039;ve removed the free spots for Kapalua and Augusta National!","breadcrumb":{"@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#primaryimage","url":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/10\/golf_1761242909.jpg","contentUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/10\/golf_1761242909.jpg","width":1440,"height":810,"caption":"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o \u2013 imagen editorial de golf"},{"@type":"BreadcrumbList","@id":"https:\/\/bolas.golf\/noticias-golf\/los-ganadores-del-pga-tour-no-viajaran-a-kapalua-ni-a-augusta-national-este-otono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bolas.golf\/"},{"@type":"ListItem","position":2,"name":"Los ganadores del PGA Tour no viajar\u00e1n a Kapalua ni a Augusta National este oto\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/bolas.golf\/en\/#website","url":"https:\/\/bolas.golf\/en\/","name":"GOLF BALLS","description":"Your golf ball specialist","publisher":{"@id":"https:\/\/bolas.golf\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bolas.golf\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bolas.golf\/en\/#organization","name":"GOLF BALLS","url":"https:\/\/bolas.golf\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bolas.golf\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/06\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp","contentUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/06\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp","width":512,"height":165,"caption":"BOLAS.GOLF"},"image":{"@id":"https:\/\/bolas.golf\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bolas.golf\/en\/#\/schema\/person\/9bcd4ea4ff7918f8583a85dbc55a3764","name":"Editor-in-Chief","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","caption":"Redactor general"},"sameAs":["http:\/\/casaclub.golf"]}]}},"_links":{"self":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/6088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/comments?post=6088"}],"version-history":[{"count":1,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/6088\/revisions"}],"predecessor-version":[{"id":6095,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/6088\/revisions\/6095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/media\/6087"}],"wp:attachment":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/media?parent=6088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/categories?post=6088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/tags?post=6088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}