{"id":5822,"date":"2025-09-29T16:58:43","date_gmt":"2025-09-29T16:58:43","guid":{"rendered":"https:\/\/bolas.golf\/?p=5822"},"modified":"2025-09-29T17:08:56","modified_gmt":"2025-09-29T17:08:56","slug":"rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup","status":"publish","type":"post","link":"https:\/\/bolas.golf\/en\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/","title":{"rendered":"Rory McIlroy criticizes the &#039;unacceptable and abusive&#039; behavior of fans at Bethpage during the Ryder Cup."},"content":{"rendered":"<p><html><body><\/p>\n<h2>Resumen<\/h2>\n<div class=\"section\">\n<p>Rory McIlroy, tras contribuir a la victoria de Europa en la Ryder Cup, no dud\u00f3 en se\u00f1alar el comportamiento hostil de la multitud de Nueva York, calific\u00e1ndolo de \u00abinaceptable y abusivo\u00bb. Durante sus cinco partidos en el campo Bethpage Black, McIlroy soport\u00f3 una avalancha de insultos que abarcaban desde su vida personal hasta fracasos pasados en el golf. Los gritos lo acompa\u00f1aron mientras se preparaba para hacer su swing y sus putts, e incluso su esposa fue alcanzada por un vaso de cerveza.<\/p>\n<p>\u201cLo que ocurri\u00f3 aqu\u00ed esta semana no es aceptable\u201d, afirm\u00f3 McIlroy el domingo, despu\u00e9s de terminar con un r\u00e9cord de 3-1-1 y ayudar a Europa a vencer a Estados Unidos 15-13. Su \u00fanica derrota fue en un partido individual contra el n\u00famero uno del mundo, Scottie Scheffler, quien tambi\u00e9n particip\u00f3 en todas las sesiones. Este enfrentamiento fue m\u00e1s un desgaste que una batalla de tiros entre los dos mejores jugadores del mundo.<\/p>\n<p>El irland\u00e9s del norte, de 36 a\u00f1os, lleg\u00f3 a Bethpage con la misi\u00f3n de conquistar su segunda Ryder Cup en suelo estadounidense. En ocasiones, se defendi\u00f3 de los abucheos, gir\u00e1ndose y maldiciendo a sus cr\u00edticos o alej\u00e1ndose de un tiro hasta que la multitud se calmara. El capit\u00e1n Luke Donald hab\u00eda anticipado un ambiente bullicioso y apasionado, incluso proporcion\u00f3 gafas de realidad virtual a los jugadores para que se acostumbraran al ruido, pero no esperaban que fuera tan grosero y desagradable.<\/p>\n<\/div>\n<h2>Detalles clave<\/h2>\n<div class=\"section\">\n<p>Durante el torneo, McIlroy pidi\u00f3 a los aficionados que \u201cse callaran\u201d antes de ejecutar un golpe decisivo. Cuando un espectador le grit\u00f3 que no era tan bueno, \u00e9l respondi\u00f3: \u201cSoy muy bueno\u201d. En la conferencia de prensa posterior a la victoria, reafirm\u00f3 su habilidad: \u201cRealmente soy bueno\u201d. Aunque a\u00fan quedaba m\u00e1s golf por jugar, McIlroy mantuvo una actitud cautelosa en las entrevistas posteriores a los partidos, sugiriendo que la gente podr\u00eda juzgar si los aficionados hab\u00edan cruzado la l\u00ednea.<\/p>\n<p>Con la Ryder Cup asegurada y las multitudes desaparecidas, el cinco veces campe\u00f3n de majors se sinti\u00f3 libre de expresar su opini\u00f3n. \u201cNo creo que debamos aceptar eso en el golf\u201d, declar\u00f3 a los reporteros, rodeado por sus compa\u00f1eros de equipo y el capit\u00e1n. \u201cEl golf deber\u00eda ser mantenido a un est\u00e1ndar m\u00e1s alto que lo que se vio esta semana\u201d. Reflexion\u00f3 sobre el deporte que lo ha hecho famoso y rico, enfatizando que el golf tiene el poder de unir a las personas y ense\u00f1arles importantes lecciones de vida, como la etiqueta y el respeto.<\/p>\n<p>McIlroy subray\u00f3 que el comportamiento inadecuado fue obra de una minor\u00eda en una multitud que en su mayor\u00eda era de \u201cverdaderos aficionados al golf\u201d, quienes respetaron a ambos equipos y les dieron la misma oportunidad de competir de manera justa. A medida que Europa comenz\u00f3 fuerte, liderando 5 1\/2 a 2 1\/2 tras el primer d\u00eda, McIlroy se convirti\u00f3 en el enemigo n\u00famero uno de una peque\u00f1a pero ruidosa parte de la afici\u00f3n estadounidense.<\/p>\n<\/div>\n<h2>Declaraciones y contexto<\/h2>\n<div class=\"section\">\n<p>Mientras los aficionados europeos lo animaban con una versi\u00f3n de una canci\u00f3n de The Cranberries adaptada a \u201cRory\u201d, los estadounidenses intentaban desestabilizarlo record\u00e1ndole su putt fallido que le cost\u00f3 el U.S. Open en 2024, burl\u00e1ndose de su altura y de su herencia irlandesa, e incluso atacando a su esposa. \u201cEstuve all\u00ed dos d\u00edas con Erica McIlroy y la cantidad de abusos que recibi\u00f3 fue asombrosa\u201d, coment\u00f3 su amigo y compa\u00f1ero de equipo Shane Lowry, elogiando el apoyo que ella brind\u00f3 a su esposo y a su equipo.<\/p>\n<p>A medida que se acercaba el final del torneo, la victoria de Europa estaba casi asegurada, con una ventaja de 11 1\/2 a 4 1\/2. Aunque Estados Unidos intent\u00f3 remontar, con la victoria de Scheffler sobre McIlroy, los aficionados se comportaron en su mayor\u00eda, con m\u00e1s de una docena de polic\u00edas estatales presentes y un mariscal advirtiendo a los espectadores que mantuvieran el respeto.<\/p>\n<p>Al final, McIlroy tuvo la \u00faltima palabra. Tras haber ganado el Masters en abril y completar el Grand Slam de su carrera, ahora ha ganado su sexta Ryder Cup en ocho intentos, mejorando su r\u00e9cord en el evento a 19-14-5. La pr\u00f3xima Ryder Cup se jugar\u00e1 en casa, en Adare Manor, Irlanda. \u201cNos aseguraremos de decir a nuestros aficionados en Irlanda en 2027 que lo que sucedi\u00f3 aqu\u00ed esta semana no es aceptable\u201d, concluy\u00f3. \u201cY para m\u00ed, es, ya sabes, ven y apoya a tu equipo local\u201d.<\/p>\n<\/div>\n<p><\/body><\/html><\/p>\n<p><script type='application\/ld+json'>\n{\"@context\": \"https:\/\/schema.org\", \"@type\": \"NewsArticle\", \"headline\": \"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder\", \"datePublished\": \"2025-09-29T16:40:19.335257+00:00\", \"dateModified\": \"2025-09-29T16:42:19.397625+00:00\", \"description\": \"Noticias Golf: Rory McIlroy critica el comportamiento abusivo de los aficionados en Bethpage durante la Ryder Cup. Noticias Golf: Rory McIlr\", \"mainEntityOfPage\": \"https:\/\/bolas.golf\", \"image\": [\"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1759164137.jpg\"]}\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rory McIlroy denounces hostile fan behavior at Bethpage after helping Europe win the Ryder Cup.<\/p>","protected":false},"author":1,"featured_media":5821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[272],"tags":[273],"class_list":["post-5822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-golf","tag-noticias-golf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup<\/title>\n<meta name=\"description\" content=\"\u2757Rory no pod\u00eda simplemente obviarlo. El golf tiene unos c\u00f3digos, una etiqueta y un saber estar. Hab\u00eda que hacer pedagog\u00eda, te cuento c\u00f3mo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolas.golf\/en\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/\"},\"author\":{\"name\":\"Redactor general\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/person\\\/9bcd4ea4ff7918f8583a85dbc55a3764\"},\"headline\":\"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup\",\"datePublished\":\"2025-09-29T16:58:43+00:00\",\"dateModified\":\"2025-09-29T17:08:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/\"},\"wordCount\":784,\"publisher\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1759164137.jpg\",\"keywords\":[\"Noticias Golf\"],\"articleSection\":[\"Noticias Golf\"],\"inLanguage\":\"en-US\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/\",\"url\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/\",\"name\":\"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1759164137.jpg\",\"datePublished\":\"2025-09-29T16:58:43+00:00\",\"dateModified\":\"2025-09-29T17:08:56+00:00\",\"description\":\"\u2757Rory no pod\u00eda simplemente obviarlo. El golf tiene unos c\u00f3digos, una etiqueta y un saber estar. Hab\u00eda que hacer pedagog\u00eda, te cuento c\u00f3mo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1759164137.jpg\",\"contentUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1759164137.jpg\",\"width\":1440,\"height\":810,\"caption\":\"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup \u2013 imagen editorial de golf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bolas.golf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bolas.golf\\\/en\\\/\",\"name\":\"BOLAS.GOLF\",\"description\":\"Tu especialista en bolas de golf\",\"publisher\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bolas.golf\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\",\"name\":\"BOLAS.GOLF\",\"url\":\"https:\\\/\\\/bolas.golf\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp\",\"contentUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp\",\"width\":512,\"height\":165,\"caption\":\"BOLAS.GOLF\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/person\\\/9bcd4ea4ff7918f8583a85dbc55a3764\",\"name\":\"Redactor general\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"caption\":\"Redactor general\"},\"sameAs\":[\"http:\\\/\\\/casaclub.golf\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rory McIlroy criticizes the &#039;unacceptable and abusive&#039; behavior of fans at Bethpage during the Ryder Cup.","description":"\u2757Rory couldn&#039;t just ignore it. Golf has its own codes, etiquette, and social graces. He needed to educate everyone, and I&#039;ll tell you how!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolas.golf\/en\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#article","isPartOf":{"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/"},"author":{"name":"Redactor general","@id":"https:\/\/bolas.golf\/en\/#\/schema\/person\/9bcd4ea4ff7918f8583a85dbc55a3764"},"headline":"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup","datePublished":"2025-09-29T16:58:43+00:00","dateModified":"2025-09-29T17:08:56+00:00","mainEntityOfPage":{"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/"},"wordCount":784,"publisher":{"@id":"https:\/\/bolas.golf\/en\/#organization"},"image":{"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#primaryimage"},"thumbnailUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1759164137.jpg","keywords":["Noticias Golf"],"articleSection":["Noticias Golf"],"inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/","url":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/","name":"Rory McIlroy criticizes the &#039;unacceptable and abusive&#039; behavior of fans at Bethpage during the Ryder Cup.","isPartOf":{"@id":"https:\/\/bolas.golf\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#primaryimage"},"image":{"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#primaryimage"},"thumbnailUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1759164137.jpg","datePublished":"2025-09-29T16:58:43+00:00","dateModified":"2025-09-29T17:08:56+00:00","description":"\u2757Rory couldn&#039;t just ignore it. Golf has its own codes, etiquette, and social graces. He needed to educate everyone, and I&#039;ll tell you how!","breadcrumb":{"@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#primaryimage","url":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1759164137.jpg","contentUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1759164137.jpg","width":1440,"height":810,"caption":"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup \u2013 imagen editorial de golf"},{"@type":"BreadcrumbList","@id":"https:\/\/bolas.golf\/noticias-golf\/rory-mcilroy-critica-el-comportamiento-inaceptable-y-abusivo-de-los-aficionados-en-bethpage-durante-la-ryder-cup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bolas.golf\/"},{"@type":"ListItem","position":2,"name":"Rory McIlroy critica el comportamiento \u2018inaceptable y abusivo\u2019 de los aficionados en Bethpage durante la Ryder Cup"}]},{"@type":"WebSite","@id":"https:\/\/bolas.golf\/en\/#website","url":"https:\/\/bolas.golf\/en\/","name":"GOLF BALLS","description":"Your golf ball specialist","publisher":{"@id":"https:\/\/bolas.golf\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bolas.golf\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bolas.golf\/en\/#organization","name":"GOLF BALLS","url":"https:\/\/bolas.golf\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bolas.golf\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/06\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp","contentUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/06\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp","width":512,"height":165,"caption":"BOLAS.GOLF"},"image":{"@id":"https:\/\/bolas.golf\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bolas.golf\/en\/#\/schema\/person\/9bcd4ea4ff7918f8583a85dbc55a3764","name":"Editor-in-Chief","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","caption":"Redactor general"},"sameAs":["http:\/\/casaclub.golf"]}]}},"_links":{"self":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/5822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/comments?post=5822"}],"version-history":[{"count":1,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/5822\/revisions"}],"predecessor-version":[{"id":5834,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/5822\/revisions\/5834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/media\/5821"}],"wp:attachment":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/media?parent=5822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/categories?post=5822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/tags?post=5822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}