{"id":5379,"date":"2025-09-14T17:34:24","date_gmt":"2025-09-14T17:34:24","guid":{"rendered":"https:\/\/bolas.golf\/?p=5379"},"modified":"2025-09-14T22:56:43","modified_gmt":"2025-09-14T22:56:43","slug":"noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente","status":"publish","type":"post","link":"https:\/\/bolas.golf\/en\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/","title":{"rendered":"Golf News: Ben Griffin maintains lead in Napa, with Scheffler closing in fast"},"content":{"rendered":"<p>NAPA, Calif. (AP) \u2014 Ben Griffin se encuentra en una posici\u00f3n delicada, con solo un golpe de ventaja en el Procore Championship, mientras dos jugadores de primer nivel lo persiguen. Uno de ellos es Jackson Koivun, un junior de Auburn y el n\u00famero uno en el ranking amateur mundial, quien ya tiene asegurada su tarjeta del PGA Tour al convertirse en profesional. El otro, m\u00e1s intimidante, es Scottie Scheffler, el n\u00famero uno del golf mundial, quien a pesar de haber tenido un doble bogey el s\u00e1bado, logr\u00f3 un impresionante 8 bajo par con 64 golpes.<\/p>\n<p>Griffin cometi\u00f3 su primer bogey del torneo en el hoyo final, finalizando con un 2 bajo par de 70 golpes, lo que redujo su ventaja a un golpe sobre Koivun y a dos sobre Scheffler. Griffin se sit\u00faa en 16 bajo par, con un total de 200 golpes. \u201cHa demostrado mucho aqu\u00ed en el tour, a pesar de que todav\u00eda est\u00e1 en la universidad\u201d, coment\u00f3 Griffin sobre Koivun, quien la semana pasada lider\u00f3 a los estadounidenses a la victoria en la Walker Cup en Cypress Point. \u201cS\u00e9 que tiene un gran juego. Est\u00e1 justo detr\u00e1s en segundo lugar en un evento del tour de cara al domingo, as\u00ed que puede jugar tan bien como Scottie y como yo\u201d, a\u00f1adi\u00f3. \u201cSolo tengo que concentrarme en m\u00ed mismo, mantenerme agresivo y tratar de hacer muchos birdies ma\u00f1ana, sin preocuparme por los dem\u00e1s.\u201d<\/p>\n<h2>Expectativas altas para el espect\u00e1culo del domingo<\/h2>\n<p>El ambiente promete ser emocionante si el s\u00e1bado fue un indicativo. La multitud fue la m\u00e1s grande desde que el torneo se traslad\u00f3 a Napa en 2014, incluso m\u00e1s que cuando Phil Mickelson particip\u00f3. Fue una oportunidad para ver a casi todos los jugadores del equipo estadounidense de la Ryder Cup en su \u00faltima aparici\u00f3n antes de dirigirse a Bethpage Black para los partidos del 26 al 28 de septiembre. La mayor\u00eda estaban all\u00ed para ver a Scheffler, con la multitud gritando \u201cScottie!\u201d y \u201cU-S-A!\u201d en la mayor\u00eda de los hoyos.<\/p>\n<p>\u201cSi salgo y juego un golf bueno y consistente, comenzar\u00e9 a avanzar en la tabla de posiciones, y ese era el objetivo de hoy\u201d, dijo Scheffler, quien comenz\u00f3 la ronda a ocho golpes de Griffin. Solo fall\u00f3 en dos greens y tuvo un gran error en el hoyo 14. Su tiro de salida se desvi\u00f3 hacia un rough blando y espeso. Se qued\u00f3 corto del green e intent\u00f3 un chip cerca de una bandera complicada, pero sali\u00f3 suave y termin\u00f3 en un mal lie en un b\u00fanker profundo. Logr\u00f3 salir a 15 pies y necesit\u00f3 dos putts para un doble bogey. Sin embargo, Scheffler respondi\u00f3 con tres birdies en sus \u00faltimos cuatro hoyos, dos de ellos en par 5, y otro birdie con un hierro 7 a 6 pies en el par 3 del hoyo 17.<\/p>\n<h2>Koivun se recupera tras un inicio dif\u00edcil<\/h2>\n<p>Koivun no comenz\u00f3 bien, con dos bogeys en los primeros hoyos, pero se recuper\u00f3 con un birdie en el par 3 del hoyo 8, y un complicado tiro desde un b\u00fanker de fairway que lo dej\u00f3 a 20 pies para un putt sin estr\u00e9s, crucial en ese momento para evitar otro tropiezo. Luego, hizo 5 bajo par en los nueve finales, incluyendo un eagle por segundo d\u00eda consecutivo en el par 5 del hoyo 12, con un putt de 40 pies. \u201cNo tuve un buen comienzo, no era lo que esperaba, pero pude darle la vuelta a la situaci\u00f3n a mitad de la ronda, hacer algunos birdies, embocar putts y mantenerme en la contienda\u201d, coment\u00f3 Koivun. Tiene la oportunidad de convertirse en el segundo amateur en ganar en el PGA Tour en dos a\u00f1os, tras Nick Dunlap en The American Express el a\u00f1o pasado. \u201cConozco bastante bien a Nick. No he hablado con \u00e9l sobre esta semana, pero definitivamente podr\u00eda querer ver su repetici\u00f3n y ver qu\u00e9 hizo.\u201d<\/p>\n<p>Por su parte, Griffin no hizo tantos birdies como en la ronda inaugural, pero logr\u00f3 mantener su distancia con tres birdies y sin errores hasta el hoyo 18. Estaba jugando su tercer tiro en el par 5 del hoyo 18 desde 127 yardas en el fairway cuando se qued\u00f3 corto ante una bandera frontal, fall\u00f3 un chip que pas\u00f3 por el green y tuvo que hacer un up-and-down para bogey. Griffin ya hab\u00eda ganado este a\u00f1o en Colonial, con Scheffler a seis golpes detr\u00e1s. Tambi\u00e9n se mantuvo en la lucha en Memorial, intentando alcanzar a Scheffler. As\u00ed que tener a los mejores del golf en la mezcla no es algo nuevo. \u201cNo me preocupa demasiado lo que \u00e9l haga. Solo tengo que jugar mejor que \u00e9l\u201d, afirm\u00f3 Griffin. \u201cY si hago eso ma\u00f1ana, deber\u00eda poder levantar el trofeo. Obviamente hay otros jugadores en la mezcla, pero creo que todos saben de lo que es capaz Scottie Scheffler y solo tengo que mantenerme adelante.\u201d<\/p>\n<p><script type='application\/ld+json'>\n{\"@context\": \"https:\/\/schema.org\", \"@type\": \"NewsArticle\", \"headline\": \"Ben Griffin mantiene un estrecho liderazgo en Napa, con un amateur acechando y Scheffler acerc\u00e1ndose r\u00e1pidamen\", \"datePublished\": \"2025-09-14T17:18:32.701912+00:00\", \"dateModified\": \"2025-09-14T17:20:38.304051+00:00\", \"description\": \"Noticias Golf: Ben Griffin lidera el Procore Championship con un golpe de ventaja, seguido de cerca por el amateur Jackson Koivun y Scottie Scheffler.\", \"mainEntityOfPage\": \"https:\/\/bolas.golf\", \"image\": [\"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1757870436.jpg\"]}\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ben Griffin clings to a one-stroke lead in Napa, while Jackson Koivun and Scottie Scheffler chase him in the Procore Championship.<\/p>","protected":false},"author":1,"featured_media":5286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[272,277],"tags":[273],"class_list":["post-5379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-golf","category-pga-tour","tag-noticias-golf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noticias Golf: Ben Griffin mantiene liderazgo en Napa, con Scheffler acerc\u00e1ndose r\u00e1pidamente<\/title>\n<meta name=\"description\" content=\"Fue una oportunidad para ver a casi todos los jugadores del equipo estadounidense de la Ryder Cup antes de dirigirse a Bethpage Black\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolas.golf\/en\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/\"},\"author\":{\"name\":\"Redactor general\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/person\\\/9bcd4ea4ff7918f8583a85dbc55a3764\"},\"headline\":\"Noticias Golf: Ben Griffin mantiene liderazgo en Napa, con Scheffler acerc\u00e1ndose r\u00e1pidamente\",\"datePublished\":\"2025-09-14T17:34:24+00:00\",\"dateModified\":\"2025-09-14T22:56:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/\"},\"wordCount\":827,\"publisher\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1757705320.jpg\",\"keywords\":[\"Noticias Golf\"],\"articleSection\":[\"Noticias Golf\",\"PGA Tour\"],\"inLanguage\":\"en-US\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/\",\"url\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/\",\"name\":\"Noticias Golf: Ben Griffin mantiene liderazgo en Napa, con Scheffler acerc\u00e1ndose r\u00e1pidamente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1757705320.jpg\",\"datePublished\":\"2025-09-14T17:34:24+00:00\",\"dateModified\":\"2025-09-14T22:56:43+00:00\",\"description\":\"Fue una oportunidad para ver a casi todos los jugadores del equipo estadounidense de la Ryder Cup antes de dirigirse a Bethpage Black\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1757705320.jpg\",\"contentUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/golf_1757705320.jpg\",\"width\":1440,\"height\":810,\"caption\":\"Mackenzie Hughes lidera en Napa mientras los equipos de la Ryder Cup obtienen resultados mixtos \u2013 imagen editorial de golf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/noticias-golf\\\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bolas.golf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias Golf: Ben Griffin mantiene liderazgo en Napa, con Scheffler acerc\u00e1ndose r\u00e1pidamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bolas.golf\\\/en\\\/\",\"name\":\"BOLAS.GOLF\",\"description\":\"Tu especialista en bolas de golf\",\"publisher\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bolas.golf\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#organization\",\"name\":\"BOLAS.GOLF\",\"url\":\"https:\\\/\\\/bolas.golf\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp\",\"contentUrl\":\"https:\\\/\\\/bolas.golf\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp\",\"width\":512,\"height\":165,\"caption\":\"BOLAS.GOLF\"},\"image\":{\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bolas.golf\\\/en\\\/#\\\/schema\\\/person\\\/9bcd4ea4ff7918f8583a85dbc55a3764\",\"name\":\"Redactor general\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g\",\"caption\":\"Redactor general\"},\"sameAs\":[\"http:\\\/\\\/casaclub.golf\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Golf News: Ben Griffin maintains lead in Napa, with Scheffler closing in fast","description":"It was an opportunity to see almost all of the players on the US Ryder Cup team before heading to Bethpage Black","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolas.golf\/en\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#article","isPartOf":{"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/"},"author":{"name":"Redactor general","@id":"https:\/\/bolas.golf\/en\/#\/schema\/person\/9bcd4ea4ff7918f8583a85dbc55a3764"},"headline":"Noticias Golf: Ben Griffin mantiene liderazgo en Napa, con Scheffler acerc\u00e1ndose r\u00e1pidamente","datePublished":"2025-09-14T17:34:24+00:00","dateModified":"2025-09-14T22:56:43+00:00","mainEntityOfPage":{"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/"},"wordCount":827,"publisher":{"@id":"https:\/\/bolas.golf\/en\/#organization"},"image":{"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#primaryimage"},"thumbnailUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1757705320.jpg","keywords":["Noticias Golf"],"articleSection":["Noticias Golf","PGA Tour"],"inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/","url":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/","name":"Golf News: Ben Griffin maintains lead in Napa, with Scheffler closing in fast","isPartOf":{"@id":"https:\/\/bolas.golf\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#primaryimage"},"image":{"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#primaryimage"},"thumbnailUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1757705320.jpg","datePublished":"2025-09-14T17:34:24+00:00","dateModified":"2025-09-14T22:56:43+00:00","description":"It was an opportunity to see almost all of the players on the US Ryder Cup team before heading to Bethpage Black","breadcrumb":{"@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#primaryimage","url":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1757705320.jpg","contentUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/09\/golf_1757705320.jpg","width":1440,"height":810,"caption":"Mackenzie Hughes lidera en Napa mientras los equipos de la Ryder Cup obtienen resultados mixtos \u2013 imagen editorial de golf"},{"@type":"BreadcrumbList","@id":"https:\/\/bolas.golf\/noticias-golf\/noticias-golf-ben-griffin-mantiene-liderazgo-en-napa-con-scheffler-acercandose-rapidamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bolas.golf\/"},{"@type":"ListItem","position":2,"name":"Noticias Golf: Ben Griffin mantiene liderazgo en Napa, con Scheffler acerc\u00e1ndose r\u00e1pidamente"}]},{"@type":"WebSite","@id":"https:\/\/bolas.golf\/en\/#website","url":"https:\/\/bolas.golf\/en\/","name":"GOLF BALLS","description":"Your golf ball specialist","publisher":{"@id":"https:\/\/bolas.golf\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bolas.golf\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bolas.golf\/en\/#organization","name":"GOLF BALLS","url":"https:\/\/bolas.golf\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bolas.golf\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/06\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp","contentUrl":"https:\/\/bolas.golf\/wp-content\/uploads\/2025\/06\/cropped-cropped-bolasgolflogo-black-transparent1-2.webp","width":512,"height":165,"caption":"BOLAS.GOLF"},"image":{"@id":"https:\/\/bolas.golf\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bolas.golf\/en\/#\/schema\/person\/9bcd4ea4ff7918f8583a85dbc55a3764","name":"Editor-in-Chief","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8e1a669d1b31f5cab6c7a076fc29610678e7fab217dc3f0ad88052406a0d7a8?s=96&d=mm&r=g","caption":"Redactor general"},"sameAs":["http:\/\/casaclub.golf"]}]}},"_links":{"self":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/5379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/comments?post=5379"}],"version-history":[{"count":2,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/5379\/revisions"}],"predecessor-version":[{"id":5386,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/posts\/5379\/revisions\/5386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/media\/5286"}],"wp:attachment":[{"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/media?parent=5379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/categories?post=5379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolas.golf\/en\/wp-json\/wp\/v2\/tags?post=5379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}